{"id":9639,"date":"2020-01-09T00:48:17","date_gmt":"2020-01-09T00:48:17","guid":{"rendered":"https:\/\/www.cleverfiles.com\/howto\/?p=9639"},"modified":"2020-01-09T00:48:17","modified_gmt":"2020-01-09T00:48:17","slug":"recovery-mode-wie-sie-ihr-ipad-den-wartungszustand-versetzen","status":"publish","type":"post","link":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html","title":{"rendered":"Recovery-Mode &#8211; Wie Sie Ihr iPad in den Wartungszustand versetzen"},"content":{"rendered":"<h2><span class=\"ez-toc-section\" id=\"ipad_recovery_mode_-_wartungszustand_leicht_gemacht\"><\/span><strong>iPad Recovery Mode &#8211; Wartungszustand leicht gemacht<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\r\n<p>Wenn Sie ein Upgrade Ihres iOS machen m\u00f6chten oder irgendwelche Probleme mit Ihrem iPad haben und das Betriebssystem neuinstallieren\u00a0wollen, m\u00fcssen Sie den\u00a0<a href=\"https:\/\/www.theiphonewiki.com\/wiki\/Recovery_Mode\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">iPad Recovery Mode<\/a>\u00a0nutzen, den Wartungszustand. Dieser Artikel zeigt Ihnen die notwendigen Schritte, um Ihr iPad in den Wartungszustand zu versetzen, und f\u00fcr den Fall, dass Sie in diesem Modus steckenbleiben, auch ein paar Hinweise darauf, wie Sie ein iPad wieder aus dem Recovery Mode herausbekommen.<\/p>\r\n<p><img class=\"border-gray border-radius-10 aligncenter wp-image-51560 size-full\" src=\"\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting.jpg\" alt=\"ipad-Wiederherstellungsmodus\" width=\"1920\" height=\"985\" srcset=\"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting.jpg 1920w, https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting-300x154.jpg 300w, https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting-500x257.jpg 500w, https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting-768x394.jpg 768w, https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting-1536x788.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\r\n<h3><span class=\"ez-toc-section\" id=\"wie_sie_ihr_ipad_in_den_wartungsmodus_versetzen\"><\/span><b>Wie Sie Ihr iPad in den Wartungsmodus versetzen<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n<ol>\r\n\t<li>\u00dcberpr\u00fcfen Sie, ob Ihr iPad aufgeladen ist. Wenn n\u00f6tig, laden Sie es auf.<\/li>\r\n\t<li>Verbinden Sie Ihr iPad mit Ihrem Computer.<\/li>\r\n\t<li>\u00d6ffnen Sie iTunes.<\/li>\r\n\t<li>Dr\u00fccken und halten Sie gleichzeitig die Standby- und die Home-Taste. Dies wird Ihr iPad zum Neustart zwingen. H\u00f6ren Sie nicht auf, zu dr\u00fccken, ehe Sie den Bildschirm f\u00fcr den Wartungsmodus des iPads sehen.<\/li>\r\n\t<li>Sie werden das iPad Wartungszustand-Men\u00fc sehen, mit den Optionen Wiederherstellen und Aktualisieren. W\u00e4hlen Sie Aktualisieren. iTunes wird versuchen, iOs neuzuinstallieren. Machen Sie sich keine Gedanken um Ihre Daten, iTunes achtet darauf, sie nicht zu l\u00f6schen. Wenn der Vorgang l\u00e4nger als 15 Minuten dauert, wiederholen Sie alle vorigen Schritte, aber w\u00e4hlen Sie diesmal bei Schritt 5 die Option Wiederherstellen. Sie haben Ihr Ger\u00e4t in den iPad-Wartungszustand versetzt.<\/li>\r\n\t<li>Richten Sie Ihr Ger\u00e4t ein.<\/li>\r\n<\/ol>\r\n<p><em>Denken Sie daran, wenn Sie Ihr Apple-Ger\u00e4t vorher gesichert haben, entweder auf iTunes oder iCloud, k\u00f6nnen Sie Ihre alten Daten wiederbekommen, indem Sie sie davon wiederherstellen.<\/em><\/p>\r\n<p><strong><em>Hinweis<\/em><\/strong>: Diese Schritte gelten f\u00fcr das iPad 2, 3 und mini.<\/p>\r\n<h3><span class=\"ez-toc-section\" id=\"wie_sie_ihr_ipad_aus_dem_wartungszustand_herausbekommen\"><\/span><b>Wie Sie Ihr iPad aus\u00a0dem Wartungszustand herausbekommen<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n<ol>\r\n\t<li>Schlie\u00dfen Sie Ihr im Wartungszustand steckengebliebenes iPad an Ihren Mac-Computer\u00a0an.<\/li>\r\n\t<li>Starten Sie iTunes auf Ihrem Mac.<\/li>\r\n\t<li>iTunes wird Ihr iPad erkennen und Ihnen erlauben, Ihr Apple iPad von einem verf\u00fcgbaren Backup wiederherzustellen.<\/li>\r\n\t<li>Trennen Sie Ihr iPad von Ihrem Mac.<\/li>\r\n\t<li>Schalten Sie Ihr iPad aus.<\/li>\r\n<\/ol>\r\n<p><em>Falls Schritt 4 nicht funktioniert, tun Sie Folgendes:<\/em><\/p>\r\n<ol>\r\n\t<li>Home- und Standby-Taste gleichzeitig dr\u00fccken. Ihr iPad wird sich abschalten.<\/li>\r\n\t<li>Dr\u00fccken und halten Sie die Home-Taste.<\/li>\r\n\t<li>Verbinden Sie Ihr iPad mit Ihrem Computer und lassen Sie die Home-Taste nicht los, bis sowohl das iTunes-Logo und die USB-Anzeige erscheinen.<\/li>\r\n<\/ol>\r\n<h3><span class=\"ez-toc-section\" id=\"weitere_tipps_und_was_sie_bedenken_sollten\"><\/span><b>Weitere Tipps und was Sie bedenken sollten<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n<ol>\r\n\t<li>Wenn die obigen Schritte nicht helfen, kontaktieren Sie den Apple Support.<\/li>\r\n\t<li>Wenn Sie keinen Zugang zu einem Apple-Computer haben, suchen Sie ein Apple-Einzelhandelsgesch\u00e4ft auf oder einen autorisierten Apple Service-Anbieter. Sie sind da, um Ihnen zu helfen.<\/li>\r\n\t<li>Machen Sie h\u00e4ufig Backups Ihrer iPad-Dateien, da Sie nie wissen, wann Sie Ihre Daten vielleicht wiederherstellen m\u00fcssen.<\/li>\r\n\t<li>Vermeiden Sie ein Jailbreaking Ihres iPads. Es ist nicht so einfach.<\/li>\r\n\t<li>Bleiben Sie auf dem Laufenden \u00fcber iPad-L\u00f6sungen.<\/li>\r\n<\/ol>\r\n<h3><span class=\"ez-toc-section\" id=\"wie_sie_ihre_verlorenen_dateien_retten\"><\/span><b>Wie Sie Ihre verlorenen Dateien retten<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\r\n<p>Wenn Sie mit dem Vorgang des Neuladens des iOS fertig sind, werden Sie vielleicht bemerken, dass einige Daten verlorengegangen sind. Zum Gl\u00fcck gibt es eine gute App zum Wiederherstellen von Daten f\u00fcr Apple-Produkte. Ihr Name ist Disk Drill und sie ist kostenfrei auf unserer Webseite erh\u00e4ltlich.<\/p>\r\n<p><img class=\"size-full wp-image-7160 aligncenter\" src=\"\/howto\/wp-content\/uploads\/2018\/03\/ddWinComicsPromo-2.jpg\" alt=\"Daten-ipad-Wiederherstellung\" width=\"640\" height=\"526\" \/> <div class=\"relative bottom download__block\">\r\n            <div class=\"d-flex align-center download__block__inner\">\r\n                <div class=\"download__block__image-wrapper\">\r\n                <div class=\"download__block__image\">\r\n                    <img src=\"\/howto\/wp-content\/uploads\/2020\/03\/sidebar-ban-96.png\" srcset=\"\/howto\/wp-content\/uploads\/2020\/03\/sidebar-ban-2x-1.png 2x\" alt=\"Disk Drill\" width=\"96\" height=\"96\">     \r\n                <\/div>\r\n                <\/div>\r\n                <div class=\"download__block__announce\">\r\n                    <b>download-block-title<\/b><br>\r\n                    download-block-text\r\n                <\/div>\r\n                <div class=\"download__block__action\">\r\n                    <a href=\"\/\/downloads.html\" data-href-mac=\/\/downloads.html data-href-win=\/\/download-disk-drill-windows.html class=\"button button-green btn-md osreplace\">\r\n<svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n<path d=\"M11.9546 7.293C11.8736 7.114 11.6956 7 11.4996 7H9.49957V0.5C9.49957 0.224 9.27557 0 8.99957 0H6.99957C6.72357 0 6.49957 0.224 6.49957 0.5V7H4.49957C4.30357 7 4.12557 7.115 4.04457 7.293C3.96257 7.472 3.99457 7.681 4.12357 7.829L7.62357 11.829C7.71857 11.938 7.85557 12 7.99957 12C8.14357 12 8.28057 11.937 8.37557 11.829L11.8756 7.829C12.0056 7.682 12.0356 7.472 11.9546 7.293Z\" fill=\"white\"\/>\r\n<path d=\"M13.5 11V14H2.5V11H0.5V15C0.5 15.553 0.948 16 1.5 16H14.5C15.053 16 15.5 15.553 15.5 15V11H13.5Z\" fill=\"white\"\/>\r\n<\/svg>\r\ndownload-block-button-text<\/a>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div><\/p>\r\n<p>Die neue Version von Disk Drill ist verf\u00fcgbar in mehr als 10 Sprachen, einschlie\u00dflich Englisch, T\u00fcrkisch, Koreanisch, Taiwanesisch, Arabisch und Malaysisch. Sie hat auch eine neue Benutzeroberfl\u00e4che und schnellere Wiederherstellungsalgorithmen.<\/p>\r\n<p>Disk Drill verbindet sich \u00fcber iTunes mit Ihrem iPad und stellt von iTunes-Backups Ihre Daten wieder her. Wenn Sie Dateien auf dem Laufwerk Ihres iPads wiederherstellen m\u00f6chten bei einer App, die sich noch im Speicher befindet, m\u00fcssen Sie ein Jailbreak Ihres iPads vornehmen und eine nicht-Apple-Technik anwenden.\u00a0<\/p>\r\n<p>Da Disk Drill von Backups auf iTunes wiederherstellt, nutzt die Software einen anderen Algorithmus zum Wiederherstellen als den Algorithmus, der f\u00fcr die Wiederherstellung von Festplatten zur Verf\u00fcgung steht. So werden Sie feststellen, dass der \u00fcbliche Quick Scan (Schnell-Scan) und Deep Scan (Tiefen-Scan), oder\u00a0Catalog Rebuild (Wiederaufbau des Katalogs) nicht verf\u00fcgbar sind. Sie sind vielleicht auch \u00fcberrascht davon, die Resultate auf einem anderen Bildschirm dargestellt zu sehen. Machen Sie sich keine Sorgen, Ihre wiederhergestellten Dateien sind alle da.<\/p>\r\n<p>Und falls Sie irgendwelche Fragen haben, sehen Sie sich einfach Disk Drills Hilfeseiten an. Sie sind auf leicht nachzuvollziehende Weise geschrieben.<\/p>\r\n<div class=\"embed-responsive embed-responsive-16by9\"><iframe class=\"embed-responsive-item\" src=\"https:\/\/www.youtube.com\/embed\/RREnPh-Gqvc\" width=\"640\" height=\"360\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"iPad Recovery Mode &#8211; Wartungszustand leicht gemacht Wenn Sie ein Upgrade Ihres iOS machen m\u00f6chten oder irgendwelche Probleme mit Ihrem iPad haben und das Betriebssystem neuinstallieren\u00a0wollen, m\u00fcssen Sie den\u00a0iPad Recovery Mode\u00a0nutzen, den Wartungszustand. Dieser Artikel zeigt Ihnen die notwendigen Schritte,&#8230;","protected":false},"author":7840,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2220],"tags":[],"class_list":{"0":"post-9639","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ios-data-recovery-de"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten\" \/>\n<meta property=\"og:description\" content=\"iPad Recovery Mode &#8211; Wartungszustand leicht gemacht Wenn Sie ein Upgrade Ihres iOS machen m\u00f6chten oder irgendwelche Probleme mit Ihrem iPad haben und das Betriebssystem neuinstallieren\u00a0wollen, m\u00fcssen Sie den\u00a0iPad Recovery Mode\u00a0nutzen, den Wartungszustand. Dieser Artikel zeigt Ihnen die notwendigen Schritte,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html\" \/>\n<meta property=\"og:site_name\" content=\"Data recovery tips. Recover deleted files on Mac, Windows.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/07\/og-cleverfiles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Cole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@Arthur_Cole_\" \/>\n<meta name=\"twitter:site\" content=\"@Cleverfiles\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Cole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html","og_locale":"en_US","og_type":"article","og_title":"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten","og_description":"iPad Recovery Mode &#8211; Wartungszustand leicht gemacht Wenn Sie ein Upgrade Ihres iOS machen m\u00f6chten oder irgendwelche Probleme mit Ihrem iPad haben und das Betriebssystem neuinstallieren\u00a0wollen, m\u00fcssen Sie den\u00a0iPad Recovery Mode\u00a0nutzen, den Wartungszustand. Dieser Artikel zeigt Ihnen die notwendigen Schritte,...","og_url":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html","og_site_name":"Data recovery tips. Recover deleted files on Mac, Windows.","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/07\/og-cleverfiles.jpg","type":"image\/jpeg"}],"author":"Arthur Cole","twitter_card":"summary_large_image","twitter_title":"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten","twitter_image":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2020\/01\/ipad-rebooting.jpg","twitter_creator":"@Arthur_Cole_","twitter_site":"@Cleverfiles","twitter_misc":{"Written by":"Arthur Cole","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html#article","isPartOf":{"@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html"},"author":{"name":"Arthur Cole","@id":"https:\/\/www.cleverfiles.com\/howto\/#\/schema\/person\/dee18a97943741568d531f8473a6e560"},"headline":"Recovery-Mode &#8211; Wie Sie Ihr iPad in den Wartungszustand versetzen","datePublished":"2020-01-09T00:48:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html"},"wordCount":697,"publisher":{"@id":"https:\/\/www.cleverfiles.com\/howto\/#organization"},"articleSection":["iOS Datenrettung"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html","url":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html","name":"Wie Sie Ihr iPad in den Wartungsmodus versetzen und verlorene Dateien retten","isPartOf":{"@id":"https:\/\/www.cleverfiles.com\/howto\/#website"},"datePublished":"2020-01-09T00:48:17+00:00","breadcrumb":{"@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cleverfiles.com\/howto\/de\/ipad-recovery-mode.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/www.cleverfiles.com\/howto\/fr\/"},{"@type":"ListItem","position":2,"name":"Recovery-Mode &#8211; Wie Sie Ihr iPad in den Wartungszustand versetzen"}]},{"@type":"WebSite","@id":"https:\/\/www.cleverfiles.com\/howto\/#website","url":"https:\/\/www.cleverfiles.com\/howto\/","name":"Data recovery tips. Recover deleted files on Mac, Windows.","description":"","publisher":{"@id":"https:\/\/www.cleverfiles.com\/howto\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cleverfiles.com\/howto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cleverfiles.com\/howto\/#organization","name":"CleverFiles","url":"https:\/\/www.cleverfiles.com\/howto\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cleverfiles.com\/howto\/#\/schema\/logo\/image\/","url":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2021\/07\/dd-mac-1024-flat.png","contentUrl":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2021\/07\/dd-mac-1024-flat.png","width":512,"height":512,"caption":"CleverFiles"},"image":{"@id":"https:\/\/www.cleverfiles.com\/howto\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Cleverfiles"]},{"@type":"Person","@id":"https:\/\/www.cleverfiles.com\/howto\/#\/schema\/person\/dee18a97943741568d531f8473a6e560","name":"Arthur Cole","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cleverfiles.com\/howto\/#\/schema\/person\/image\/","url":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2019\/07\/Arthur_Cole-96x96.jpg","contentUrl":"https:\/\/www.cleverfiles.com\/howto\/wp-content\/uploads\/2019\/07\/Arthur_Cole-96x96.jpg","caption":"Arthur Cole"},"description":"Arthur Cole is a freelance content creator. He also has a more than 10-year experience in program development for macOS, Windows, iOS, Android. Arthur Cole is a writer with deep expertise in programming, who can easily jump into development processes on any modern platform, be it Windows, Mac, iOS, or Android, being at the same time a capable storyteller of all things IT. He often comes up with great ideas and innovative input, which makes him an indispensable part on his myriad of teams. He really likes writing. Unlike others, he also likes seeing others reading his content, of course. He created articles about Technology, Podcast and Gaming Industries, End-User and Corporate Software, Hardware, and so on. Over the years, he wrote hundreds of articles and tutorials on sites such as DZone, Simpleprogrammer, Ingeniumweb, Themanifest, Enterprisenetworkingplanet, aboutssl.org and many more. Arthur has been an essential part of various marketing campaigns for CleverFiles, maintained great relationships with our partners, and was pretty much always a frontman at various conferences, ensuring a connection with fellow IT entrepreneurs. He is a great animal lover and hiking enthusiast. Loves exploring new trails and beaches with his dog Angus and has recently been getting his hands and knees dirty in the garden.","sameAs":["https:\/\/x.com\/Arthur_Cole_"],"url":"https:\/\/www.cleverfiles.com\/howto\/author\/arthur-cole\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/posts\/9639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/users\/7840"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/comments?post=9639"}],"version-history":[{"count":8,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/posts\/9639\/revisions"}],"predecessor-version":[{"id":51563,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/posts\/9639\/revisions\/51563"}],"wp:attachment":[{"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/media?parent=9639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/categories?post=9639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cleverfiles.com\/howto\/wp-json\/wp\/v2\/tags?post=9639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}